{"id":825,"date":"2022-04-08T10:50:42","date_gmt":"2022-04-08T09:50:42","guid":{"rendered":"https:\/\/rete-ries.it\/stage\/?p=825"},"modified":"2022-04-12T08:29:20","modified_gmt":"2022-04-12T07:29:20","slug":"il-dess-bg-organizza-la-partecipazione-alla-marcia-perugia-assisi","status":"publish","type":"post","link":"https:\/\/rete-ries.it\/stage\/notizie-soci\/il-dess-bg-organizza-la-partecipazione-alla-marcia-perugia-assisi\/","title":{"rendered":"Il Dess Bg organizza la partecipazione alla marcia Perugia-Assisi"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.15&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.15&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.15&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/rete-ries.it\/stage\/wp-content\/uploads\/2022\/04\/marcia-pace-aprile-2022.jpg&#8221; title_text=&#8221;marcia pace aprile 2022&#8243; align=&#8221;center&#8221; _builder_version=&#8221;4.15.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.15.0&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><!-- divi:paragraph --><\/p>\n<div class=\"kvgmc6g5 cxmmr5t8 oygrvhab hcukyx3x c1et5uql ii04i59q\">\n<div dir=\"auto\">\n<p>Il Dess Bg &#8211; Distretto dell&#8217;economia sociale e solidale bergamasco, in collaborazione con Fondazione Istituti Educativi, organizza un pullman per raggiungere l&#8217;Umbria e aderire all&#8217;edizione straordinaria della Marcia per la pace e la fraternit\u00e0 PerugiAssisi convocata per il prossimo 24 aprile.<\/p>\n<p>In un momento storico in cui la politica italiana, alla pari di altri Paesi nel mondo, sta seguendo la strada del riarmo per affrontare l&#8217;urgenza della conflitto in Ucraina, gli organizzatori della PerugiAssisi hanno richiamato i pacifisti di tutta Italia, gli istituti scolastici e le realt\u00e0 associative nazionali a partecipare ad una nuova marcia per dire basta alla violenza, rilanciando l&#8217;appello di Papa Francesco: &#8220;Fermatevi! La guerra \u00e8 una follia&#8221;.<br \/>I temi fondamentali su cui vogliamo caratterizzare la nostra adesione sono il disarmo, la fratellanza tra i popoli, la finanza etica e l&#8217;economia di giustizia.<\/p>\n<\/div>\n<\/div>\n<div class=\"cxmmr5t8 oygrvhab hcukyx3x c1et5uql o9v6fnle ii04i59q\">\n<div dir=\"auto\">Si parte alle 00.30 di domenica 24 dal Lazzaretto di Bergamo e si rientra per sera.<\/div>\n<div dir=\"auto\">Costo del pullman 30 euro<\/div>\n<\/div>\n<div class=\"cxmmr5t8 oygrvhab hcukyx3x c1et5uql o9v6fnle ii04i59q\">\n<div dir=\"auto\">Per prenotare:<\/div>\n<div dir=\"auto\">dess.bergamo@gmail.com<\/div>\n<div dir=\"auto\">3480469799<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p><!-- \/divi:paragraph --><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.15&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.15&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_button button_url=&#8221;https:\/\/dess.bg.it\/evento\/marcia-straordinaria-della-pace-perugiassisi\/&#8221; url_new_window=&#8221;on&#8221; button_text=&#8221;Vai all&#8217;evento sul sito Dess Bg&#8221; _builder_version=&#8221;4.15.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Dess Bg &#8211; Distretto dell&#8217;economia sociale e solidale bergamasco, in collaborazione con Fondazione Istituti Educativi, organizza un pullman per raggiungere l&#8217;Umbria e aderire all&#8217;edizione straordinaria della Marcia per la [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":833,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[17],"tags":[22,27,45],"class_list":["post-825","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-soci","tag-dessbg","tag-guerra","tag-pace","et-has-post-format-content","et_post_format-et-post-format-standard"],"_links":{"self":[{"href":"https:\/\/rete-ries.it\/stage\/wp-json\/wp\/v2\/posts\/825","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rete-ries.it\/stage\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rete-ries.it\/stage\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rete-ries.it\/stage\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/rete-ries.it\/stage\/wp-json\/wp\/v2\/comments?post=825"}],"version-history":[{"count":7,"href":"https:\/\/rete-ries.it\/stage\/wp-json\/wp\/v2\/posts\/825\/revisions"}],"predecessor-version":[{"id":836,"href":"https:\/\/rete-ries.it\/stage\/wp-json\/wp\/v2\/posts\/825\/revisions\/836"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rete-ries.it\/stage\/wp-json\/wp\/v2\/media\/833"}],"wp:attachment":[{"href":"https:\/\/rete-ries.it\/stage\/wp-json\/wp\/v2\/media?parent=825"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rete-ries.it\/stage\/wp-json\/wp\/v2\/categories?post=825"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rete-ries.it\/stage\/wp-json\/wp\/v2\/tags?post=825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}