{"id":2,"name":"Simonetta Rinaldi","url":"","description":"","link":"https:\/\/rete-ries.it\/stage\/author\/simories\/","slug":"simories","avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/55e44cf8fcaf946399f31bc8be3c0ea4e4117ea61e4b904b9e415a252bd38eef?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/55e44cf8fcaf946399f31bc8be3c0ea4e4117ea61e4b904b9e415a252bd38eef?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/55e44cf8fcaf946399f31bc8be3c0ea4e4117ea61e4b904b9e415a252bd38eef?s=96&d=mm&r=g"},"meta":[],"_links":{"self":[{"href":"https:\/\/rete-ries.it\/stage\/wp-json\/wp\/v2\/users\/2","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rete-ries.it\/stage\/wp-json\/wp\/v2\/users"}]}}